{"id":10073,"date":"2014-11-20T09:29:26","date_gmt":"2014-11-20T09:29:26","guid":{"rendered":"http:\/\/dev.joomexp.com\/wordpress\/wp-yamato\/?page_id=10073"},"modified":"2022-06-03T03:07:43","modified_gmt":"2022-06-03T03:07:43","slug":"portfolio-4-columns-style-2","status":"publish","type":"page","link":"https:\/\/demo.exptheme.com\/yamato\/portfolio-4-columns-style-2\/","title":{"rendered":"Portfolio 4 Columns Style 2"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row css=&#8221;.vc_custom_1654055571763{padding-top: 40px !important;padding-bottom: 70px !important;}&#8221;][vc_column]<div id=\"cs_portfolio_filters_true\" class=\"cs_portfolio_filters\" style=\"text-align: Center\">\r\n    <ul class=\"list-unstyled btn-group\">\r\n        <li class=\"active\"><a class=\"\" href=\"#\" data-filter=\"*\">All<\/a><\/li>\r\n                        <li class=\"filter-items\">\r\n                    <a href=\"#\" term-id=\"38\" data-filter=\".apps\">\r\n                        Apps                    <\/a>\r\n                <\/li>\r\n                                <li class=\"filter-items\">\r\n                    <a href=\"#\" term-id=\"41\" data-filter=\".design-2\">\r\n                        Design                    <\/a>\r\n                <\/li>\r\n                                <li class=\"filter-items\">\r\n                    <a href=\"#\" term-id=\"59\" data-filter=\".development\">\r\n                        Development                    <\/a>\r\n                <\/li>\r\n                                <li class=\"filter-items\">\r\n                    <a href=\"#\" term-id=\"46\" data-filter=\".logo-design\">\r\n                        Logo Design                    <\/a>\r\n                <\/li>\r\n                                <li class=\"filter-items\">\r\n                    <a href=\"#\" term-id=\"49\" data-filter=\".print-design\">\r\n                        Print Design                    <\/a>\r\n                <\/li>\r\n                                <li class=\"filter-items\">\r\n                    <a href=\"#\" term-id=\"52\" data-filter=\".survey\">\r\n                        Survey                    <\/a>\r\n                <\/li>\r\n                                <li class=\"filter-items\">\r\n                    <a href=\"#\" term-id=\"53\" data-filter=\".video\">\r\n                        Video                    <\/a>\r\n                <\/li>\r\n                                <li class=\"filter-items\">\r\n                    <a href=\"#\" term-id=\"54\" data-filter=\".work\">\r\n                        Web Design                    <\/a>\r\n                <\/li>\r\n                    <\/ul>\r\n<\/div>\r\n<div id=\"cs_portfolio_1\" class=\"cs-portfolio cs-portfolio-layout-3 portfolio_6a9807f735aa0 cs-portfolio-col4 layout-3\" data-columns=\"4\" data-type=\"grid\"><div class='cs-portfolio-item class-test development ' data-id='10106'><style type=\"text\/css\" scoped>\r\n    #cs_portfolio_1 .cs-portfolio-container a{\r\n            }\r\n    #cs_portfolio_1 .cs-portfolio-container a:hover{\r\n            }\r\n    #cs_portfolio_1.cs-portfolio{\r\n        margin: 0 -10px;    }\r\n<\/style>\r\n<div class=\"cs-portfolio-container\" style=\"margin:10px;\">\r\n    <article id=\"post-10106\" class=\"post-10106 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-development\">\r\n        <div class=\"cs-portfolio-header \">\r\n            <div class=\"cs-portfolio-header-meta\">\r\n                <img decoding=\"async\" alt=\"\" class=\"attachment-featuredImageCropped\" src=\"https:\/\/demo.exptheme.com\/yamato\/wp-content\/uploads\/2014\/11\/9-300x200_c.jpg\" \/>                <div class=\"link-wrap\">\r\n                    <a data-csrel=\"tooltip\" data-original-title=\"Large Image\" href=\"https:\/\/demo.exptheme.com\/yamato\/wp-content\/uploads\/2014\/11\/9-1024x700.jpg\" class=\"cs-zoom colorbox\"><span class=\"cs-meta-zoom\"><i class=\"fa fa-expand\"><\/i>\r\n<\/span><\/a><a data-csrel=\"tooltip\" data-original-title=\"Read more\" class=\"cs-read-more\" title=\"\" href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio\/work9\/\" ><i class=\"fa fa-sign-out\"><\/i><\/a>                <\/div>\r\n            <\/div>    \r\n            <div class=\"cs-portfolio-content-wrap\" style=\"background-color:;\">\r\n                <div class=\"cs-portfolio-meta-box\">\r\n                    <div class=\"cs-portfolio-category\"><a href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio_category\/development\/\" rel=\"tag\">Development<\/a><\/div><h4 class=\"cs-portfolio-title\"><a style=\"color:!important;\" title=\"Work9\" href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio\/work9\/\" >Work9<\/a><\/h4>                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/article>\r\n<\/div>\r\n<\/div><div class='cs-portfolio-item class-test video ' data-id='10087'><style type=\"text\/css\" scoped>\r\n    #cs_portfolio_1 .cs-portfolio-container a{\r\n            }\r\n    #cs_portfolio_1 .cs-portfolio-container a:hover{\r\n            }\r\n    #cs_portfolio_1.cs-portfolio{\r\n        margin: 0 -10px;    }\r\n<\/style>\r\n<div class=\"cs-portfolio-container\" style=\"margin:10px;\">\r\n    <article id=\"post-10087\" class=\"post-10087 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-video\">\r\n        <div class=\"cs-portfolio-header \">\r\n            <div class=\"cs-portfolio-header-meta\">\r\n                <img decoding=\"async\" alt=\"\" class=\"attachment-featuredImageCropped\" src=\"https:\/\/demo.exptheme.com\/yamato\/wp-content\/uploads\/2014\/11\/9-300x200_c.jpg\" \/>                <div class=\"link-wrap\">\r\n                    <a data-csrel=\"tooltip\" data-original-title=\"Large Image\" href=\"https:\/\/demo.exptheme.com\/yamato\/wp-content\/uploads\/2014\/11\/9-1024x700.jpg\" class=\"cs-zoom colorbox\"><span class=\"cs-meta-zoom\"><i class=\"fa fa-expand\"><\/i>\r\n<\/span><\/a><a data-csrel=\"tooltip\" data-original-title=\"Read more\" class=\"cs-read-more\" title=\"\" href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio\/logo-design\/\" ><i class=\"fa fa-sign-out\"><\/i><\/a>                <\/div>\r\n            <\/div>    \r\n            <div class=\"cs-portfolio-content-wrap\" style=\"background-color:;\">\r\n                <div class=\"cs-portfolio-meta-box\">\r\n                    <div class=\"cs-portfolio-category\"><a href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio_category\/video\/\" rel=\"tag\">Video<\/a><\/div><h4 class=\"cs-portfolio-title\"><a style=\"color:!important;\" title=\"Logo Design\" href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio\/logo-design\/\" >Logo Design<\/a><\/h4>                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/article>\r\n<\/div>\r\n<\/div><div class='cs-portfolio-item class-test video ' data-id='10086'><style type=\"text\/css\" scoped>\r\n    #cs_portfolio_1 .cs-portfolio-container a{\r\n            }\r\n    #cs_portfolio_1 .cs-portfolio-container a:hover{\r\n            }\r\n    #cs_portfolio_1.cs-portfolio{\r\n        margin: 0 -10px;    }\r\n<\/style>\r\n<div class=\"cs-portfolio-container\" style=\"margin:10px;\">\r\n    <article id=\"post-10086\" class=\"post-10086 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-video\">\r\n        <div class=\"cs-portfolio-header \">\r\n            <div class=\"cs-portfolio-header-meta\">\r\n                <img decoding=\"async\" alt=\"\" class=\"attachment-featuredImageCropped\" src=\"https:\/\/demo.exptheme.com\/yamato\/wp-content\/uploads\/2014\/11\/5-300x200_c.jpg\" \/>                <div class=\"link-wrap\">\r\n                    <a data-csrel=\"tooltip\" data-original-title=\"Large Image\" href=\"https:\/\/demo.exptheme.com\/yamato\/wp-content\/uploads\/2014\/11\/5-1024x700.jpg\" class=\"cs-zoom colorbox\"><span class=\"cs-meta-zoom\"><i class=\"fa fa-expand\"><\/i>\r\n<\/span><\/a><a data-csrel=\"tooltip\" data-original-title=\"Read more\" class=\"cs-read-more\" title=\"\" href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio\/corporate-identity\/\" ><i class=\"fa fa-sign-out\"><\/i><\/a>                <\/div>\r\n            <\/div>    \r\n            <div class=\"cs-portfolio-content-wrap\" style=\"background-color:;\">\r\n                <div class=\"cs-portfolio-meta-box\">\r\n                    <div class=\"cs-portfolio-category\"><a href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio_category\/video\/\" rel=\"tag\">Video<\/a><\/div><h4 class=\"cs-portfolio-title\"><a style=\"color:!important;\" title=\"Corporate Identity\" href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio\/corporate-identity\/\" >Corporate Identity<\/a><\/h4>                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/article>\r\n<\/div>\r\n<\/div><div class='cs-portfolio-item class-test video ' data-id='10085'><style type=\"text\/css\" scoped>\r\n    #cs_portfolio_1 .cs-portfolio-container a{\r\n            }\r\n    #cs_portfolio_1 .cs-portfolio-container a:hover{\r\n            }\r\n    #cs_portfolio_1.cs-portfolio{\r\n        margin: 0 -10px;    }\r\n<\/style>\r\n<div class=\"cs-portfolio-container\" style=\"margin:10px;\">\r\n    <article id=\"post-10085\" class=\"post-10085 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-video\">\r\n        <div class=\"cs-portfolio-header \">\r\n            <div class=\"cs-portfolio-header-meta\">\r\n                <img decoding=\"async\" alt=\"\" class=\"attachment-featuredImageCropped\" src=\"https:\/\/demo.exptheme.com\/yamato\/wp-content\/uploads\/2014\/11\/1-300x200_c.jpg\" \/>                <div class=\"link-wrap\">\r\n                    <a data-csrel=\"tooltip\" data-original-title=\"Large Image\" href=\"https:\/\/demo.exptheme.com\/yamato\/wp-content\/uploads\/2014\/11\/1-1024x700.jpg\" class=\"cs-zoom colorbox\"><span class=\"cs-meta-zoom\"><i class=\"fa fa-expand\"><\/i>\r\n<\/span><\/a><a data-csrel=\"tooltip\" data-original-title=\"Read more\" class=\"cs-read-more\" title=\"\" href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio\/mobile-app-development\/\" ><i class=\"fa fa-sign-out\"><\/i><\/a>                <\/div>\r\n            <\/div>    \r\n            <div class=\"cs-portfolio-content-wrap\" style=\"background-color:;\">\r\n                <div class=\"cs-portfolio-meta-box\">\r\n                    <div class=\"cs-portfolio-category\"><a href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio_category\/video\/\" rel=\"tag\">Video<\/a><\/div><h4 class=\"cs-portfolio-title\"><a style=\"color:!important;\" title=\"Mobile App Development\" href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio\/mobile-app-development\/\" >Mobile App Development<\/a><\/h4>                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/article>\r\n<\/div>\r\n<\/div><div class='cs-portfolio-item class-test survey ' data-id='10084'><style type=\"text\/css\" scoped>\r\n    #cs_portfolio_1 .cs-portfolio-container a{\r\n            }\r\n    #cs_portfolio_1 .cs-portfolio-container a:hover{\r\n            }\r\n    #cs_portfolio_1.cs-portfolio{\r\n        margin: 0 -10px;    }\r\n<\/style>\r\n<div class=\"cs-portfolio-container\" style=\"margin:10px;\">\r\n    <article id=\"post-10084\" class=\"post-10084 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-survey\">\r\n        <div class=\"cs-portfolio-header \">\r\n            <div class=\"cs-portfolio-header-meta\">\r\n                <img decoding=\"async\" alt=\"\" class=\"attachment-featuredImageCropped\" src=\"https:\/\/demo.exptheme.com\/yamato\/wp-content\/uploads\/2014\/11\/7-300x200_c.jpg\" \/>                <div class=\"link-wrap\">\r\n                    <a data-csrel=\"tooltip\" data-original-title=\"Large Image\" href=\"https:\/\/demo.exptheme.com\/yamato\/wp-content\/uploads\/2014\/11\/7-1024x700.jpg\" class=\"cs-zoom colorbox\"><span class=\"cs-meta-zoom\"><i class=\"fa fa-expand\"><\/i>\r\n<\/span><\/a><a data-csrel=\"tooltip\" data-original-title=\"Read more\" class=\"cs-read-more\" title=\"\" href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio\/social-media-optimization\/\" ><i class=\"fa fa-sign-out\"><\/i><\/a>                <\/div>\r\n            <\/div>    \r\n            <div class=\"cs-portfolio-content-wrap\" style=\"background-color:;\">\r\n                <div class=\"cs-portfolio-meta-box\">\r\n                    <div class=\"cs-portfolio-category\"><a href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio_category\/survey\/\" rel=\"tag\">Survey<\/a><\/div><h4 class=\"cs-portfolio-title\"><a style=\"color:!important;\" title=\"Social Media Optimization\" href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio\/social-media-optimization\/\" >Social Media Optimization<\/a><\/h4>                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/article>\r\n<\/div>\r\n<\/div><div class='cs-portfolio-item class-test survey ' data-id='10083'><style type=\"text\/css\" scoped>\r\n    #cs_portfolio_1 .cs-portfolio-container a{\r\n            }\r\n    #cs_portfolio_1 .cs-portfolio-container a:hover{\r\n            }\r\n    #cs_portfolio_1.cs-portfolio{\r\n        margin: 0 -10px;    }\r\n<\/style>\r\n<div class=\"cs-portfolio-container\" style=\"margin:10px;\">\r\n    <article id=\"post-10083\" class=\"post-10083 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-survey\">\r\n        <div class=\"cs-portfolio-header \">\r\n            <div class=\"cs-portfolio-header-meta\">\r\n                <img decoding=\"async\" alt=\"\" class=\"attachment-featuredImageCropped\" src=\"https:\/\/demo.exptheme.com\/yamato\/wp-content\/uploads\/2014\/11\/3-300x200_c.jpg\" \/>                <div class=\"link-wrap\">\r\n                    <a data-csrel=\"tooltip\" data-original-title=\"Large Image\" href=\"https:\/\/demo.exptheme.com\/yamato\/wp-content\/uploads\/2014\/11\/3-1024x700.jpg\" class=\"cs-zoom colorbox\"><span class=\"cs-meta-zoom\"><i class=\"fa fa-expand\"><\/i>\r\n<\/span><\/a><a data-csrel=\"tooltip\" data-original-title=\"Read more\" class=\"cs-read-more\" title=\"\" href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio\/web-site-design\/\" ><i class=\"fa fa-sign-out\"><\/i><\/a>                <\/div>\r\n            <\/div>    \r\n            <div class=\"cs-portfolio-content-wrap\" style=\"background-color:;\">\r\n                <div class=\"cs-portfolio-meta-box\">\r\n                    <div class=\"cs-portfolio-category\"><a href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio_category\/survey\/\" rel=\"tag\">Survey<\/a><\/div><h4 class=\"cs-portfolio-title\"><a style=\"color:!important;\" title=\"Web Site Design\" href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio\/web-site-design\/\" >Web Site Design<\/a><\/h4>                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/article>\r\n<\/div>\r\n<\/div><div class='cs-portfolio-item class-test design-2 ' data-id='10082'><style type=\"text\/css\" scoped>\r\n    #cs_portfolio_1 .cs-portfolio-container a{\r\n            }\r\n    #cs_portfolio_1 .cs-portfolio-container a:hover{\r\n            }\r\n    #cs_portfolio_1.cs-portfolio{\r\n        margin: 0 -10px;    }\r\n<\/style>\r\n<div class=\"cs-portfolio-container\" style=\"margin:10px;\">\r\n    <article id=\"post-10082\" class=\"post-10082 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-design-2\">\r\n        <div class=\"cs-portfolio-header \">\r\n            <div class=\"cs-portfolio-header-meta\">\r\n                <img decoding=\"async\" alt=\"\" class=\"attachment-featuredImageCropped\" src=\"https:\/\/demo.exptheme.com\/yamato\/wp-content\/uploads\/2014\/11\/8-300x200_c.jpg\" \/>                <div class=\"link-wrap\">\r\n                    <a data-csrel=\"tooltip\" data-original-title=\"Large Image\" href=\"https:\/\/demo.exptheme.com\/yamato\/wp-content\/uploads\/2014\/11\/8-1024x700.jpg\" class=\"cs-zoom colorbox\"><span class=\"cs-meta-zoom\"><i class=\"fa fa-expand\"><\/i>\r\n<\/span><\/a><a data-csrel=\"tooltip\" data-original-title=\"Read more\" class=\"cs-read-more\" title=\"\" href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio\/video-advertisement\/\" ><i class=\"fa fa-sign-out\"><\/i><\/a>                <\/div>\r\n            <\/div>    \r\n            <div class=\"cs-portfolio-content-wrap\" style=\"background-color:;\">\r\n                <div class=\"cs-portfolio-meta-box\">\r\n                    <div class=\"cs-portfolio-category\"><a href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio_category\/design-2\/\" rel=\"tag\">Design<\/a><\/div><h4 class=\"cs-portfolio-title\"><a style=\"color:!important;\" title=\"Video Advertisement\" href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio\/video-advertisement\/\" >Video Advertisement<\/a><\/h4>                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/article>\r\n<\/div>\r\n<\/div><div class='cs-portfolio-item class-test design-2 ' data-id='10081'><style type=\"text\/css\" scoped>\r\n    #cs_portfolio_1 .cs-portfolio-container a{\r\n            }\r\n    #cs_portfolio_1 .cs-portfolio-container a:hover{\r\n            }\r\n    #cs_portfolio_1.cs-portfolio{\r\n        margin: 0 -10px;    }\r\n<\/style>\r\n<div class=\"cs-portfolio-container\" style=\"margin:10px;\">\r\n    <article id=\"post-10081\" class=\"post-10081 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-design-2\">\r\n        <div class=\"cs-portfolio-header \">\r\n            <div class=\"cs-portfolio-header-meta\">\r\n                <img decoding=\"async\" alt=\"\" class=\"attachment-featuredImageCropped\" src=\"https:\/\/demo.exptheme.com\/yamato\/wp-content\/uploads\/2014\/11\/4-300x200_c.jpg\" \/>                <div class=\"link-wrap\">\r\n                    <a data-csrel=\"tooltip\" data-original-title=\"Large Image\" href=\"https:\/\/demo.exptheme.com\/yamato\/wp-content\/uploads\/2014\/11\/4-1024x700.jpg\" class=\"cs-zoom colorbox\"><span class=\"cs-meta-zoom\"><i class=\"fa fa-expand\"><\/i>\r\n<\/span><\/a><a data-csrel=\"tooltip\" data-original-title=\"Read more\" class=\"cs-read-more\" title=\"\" href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio\/t-shirt-stamp-design\/\" ><i class=\"fa fa-sign-out\"><\/i><\/a>                <\/div>\r\n            <\/div>    \r\n            <div class=\"cs-portfolio-content-wrap\" style=\"background-color:;\">\r\n                <div class=\"cs-portfolio-meta-box\">\r\n                    <div class=\"cs-portfolio-category\"><a href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio_category\/design-2\/\" rel=\"tag\">Design<\/a><\/div><h4 class=\"cs-portfolio-title\"><a style=\"color:!important;\" title=\"T-Shirt Stamp Design\" href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio\/t-shirt-stamp-design\/\" >T-Shirt Stamp Design<\/a><\/h4>                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/article>\r\n<\/div>\r\n<\/div><div class='cs-portfolio-item class-test apps ' data-id='10080'><style type=\"text\/css\" scoped>\r\n    #cs_portfolio_1 .cs-portfolio-container a{\r\n            }\r\n    #cs_portfolio_1 .cs-portfolio-container a:hover{\r\n            }\r\n    #cs_portfolio_1.cs-portfolio{\r\n        margin: 0 -10px;    }\r\n<\/style>\r\n<div class=\"cs-portfolio-container\" style=\"margin:10px;\">\r\n    <article id=\"post-10080\" class=\"post-10080 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-apps\">\r\n        <div class=\"cs-portfolio-header \">\r\n            <div class=\"cs-portfolio-header-meta\">\r\n                <img decoding=\"async\" alt=\"\" class=\"attachment-featuredImageCropped\" src=\"https:\/\/demo.exptheme.com\/yamato\/wp-content\/uploads\/2014\/11\/6-300x200_c.jpg\" \/>                <div class=\"link-wrap\">\r\n                    <a data-csrel=\"tooltip\" data-original-title=\"Large Image\" href=\"https:\/\/demo.exptheme.com\/yamato\/wp-content\/uploads\/2014\/11\/6-1024x700.jpg\" class=\"cs-zoom colorbox\"><span class=\"cs-meta-zoom\"><i class=\"fa fa-expand\"><\/i>\r\n<\/span><\/a><a data-csrel=\"tooltip\" data-original-title=\"Read more\" class=\"cs-read-more\" title=\"\" href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio\/iphone-4s-case-design\/\" ><i class=\"fa fa-sign-out\"><\/i><\/a>                <\/div>\r\n            <\/div>    \r\n            <div class=\"cs-portfolio-content-wrap\" style=\"background-color:;\">\r\n                <div class=\"cs-portfolio-meta-box\">\r\n                    <div class=\"cs-portfolio-category\"><a href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio_category\/apps\/\" rel=\"tag\">Apps<\/a><\/div><h4 class=\"cs-portfolio-title\"><a style=\"color:!important;\" title=\"iPhone 4S Case Design\" href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio\/iphone-4s-case-design\/\" >iPhone 4S Case Design<\/a><\/h4>                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/article>\r\n<\/div>\r\n<\/div><div class='cs-portfolio-item class-test apps ' data-id='10079'><style type=\"text\/css\" scoped>\r\n    #cs_portfolio_1 .cs-portfolio-container a{\r\n            }\r\n    #cs_portfolio_1 .cs-portfolio-container a:hover{\r\n            }\r\n    #cs_portfolio_1.cs-portfolio{\r\n        margin: 0 -10px;    }\r\n<\/style>\r\n<div class=\"cs-portfolio-container\" style=\"margin:10px;\">\r\n    <article id=\"post-10079\" class=\"post-10079 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-apps\">\r\n        <div class=\"cs-portfolio-header \">\r\n            <div class=\"cs-portfolio-header-meta\">\r\n                <img decoding=\"async\" alt=\"\" class=\"attachment-featuredImageCropped\" src=\"https:\/\/demo.exptheme.com\/yamato\/wp-content\/uploads\/2014\/11\/2-300x200_c.jpg\" \/>                <div class=\"link-wrap\">\r\n                    <a data-csrel=\"tooltip\" data-original-title=\"Large Image\" href=\"https:\/\/demo.exptheme.com\/yamato\/wp-content\/uploads\/2014\/11\/2-1024x700.jpg\" class=\"cs-zoom colorbox\"><span class=\"cs-meta-zoom\"><i class=\"fa fa-expand\"><\/i>\r\n<\/span><\/a><a data-csrel=\"tooltip\" data-original-title=\"Read more\" class=\"cs-read-more\" title=\"\" href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio\/soda-can-design\/\" ><i class=\"fa fa-sign-out\"><\/i><\/a>                <\/div>\r\n            <\/div>    \r\n            <div class=\"cs-portfolio-content-wrap\" style=\"background-color:;\">\r\n                <div class=\"cs-portfolio-meta-box\">\r\n                    <div class=\"cs-portfolio-category\"><a href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio_category\/apps\/\" rel=\"tag\">Apps<\/a><\/div><h4 class=\"cs-portfolio-title\"><a style=\"color:!important;\" title=\"Soda Can Design\" href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio\/soda-can-design\/\" >Soda Can Design<\/a><\/h4>                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/article>\r\n<\/div>\r\n<\/div><div class='cs-portfolio-item class-test work ' data-id='9849'><style type=\"text\/css\" scoped>\r\n    #cs_portfolio_1 .cs-portfolio-container a{\r\n            }\r\n    #cs_portfolio_1 .cs-portfolio-container a:hover{\r\n            }\r\n    #cs_portfolio_1.cs-portfolio{\r\n        margin: 0 -10px;    }\r\n<\/style>\r\n<div class=\"cs-portfolio-container\" style=\"margin:10px;\">\r\n    <article id=\"post-9849\" class=\"post-9849 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-work\">\r\n        <div class=\"cs-portfolio-header \">\r\n            <div class=\"cs-portfolio-header-meta\">\r\n                <img decoding=\"async\" alt=\"\" class=\"attachment-featuredImageCropped\" src=\"https:\/\/demo.exptheme.com\/yamato\/wp-content\/uploads\/2014\/11\/8-300x200_c.jpg\" \/>                <div class=\"link-wrap\">\r\n                    <a data-csrel=\"tooltip\" data-original-title=\"Large Image\" href=\"https:\/\/demo.exptheme.com\/yamato\/wp-content\/uploads\/2014\/11\/8-1024x700.jpg\" class=\"cs-zoom colorbox\"><span class=\"cs-meta-zoom\"><i class=\"fa fa-expand\"><\/i>\r\n<\/span><\/a><a data-csrel=\"tooltip\" data-original-title=\"Read more\" class=\"cs-read-more\" title=\"\" href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio\/work8\/\" ><i class=\"fa fa-sign-out\"><\/i><\/a>                <\/div>\r\n            <\/div>    \r\n            <div class=\"cs-portfolio-content-wrap\" style=\"background-color:;\">\r\n                <div class=\"cs-portfolio-meta-box\">\r\n                    <div class=\"cs-portfolio-category\"><a href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio_category\/work\/\" rel=\"tag\">Web Design<\/a><\/div><h4 class=\"cs-portfolio-title\"><a style=\"color:!important;\" title=\"Work8\" href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio\/work8\/\" >Work8<\/a><\/h4>                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/article>\r\n<\/div>\r\n<\/div><div class='cs-portfolio-item class-test work ' data-id='9848'><style type=\"text\/css\" scoped>\r\n    #cs_portfolio_1 .cs-portfolio-container a{\r\n            }\r\n    #cs_portfolio_1 .cs-portfolio-container a:hover{\r\n            }\r\n    #cs_portfolio_1.cs-portfolio{\r\n        margin: 0 -10px;    }\r\n<\/style>\r\n<div class=\"cs-portfolio-container\" style=\"margin:10px;\">\r\n    <article id=\"post-9848\" class=\"post-9848 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-work\">\r\n        <div class=\"cs-portfolio-header \">\r\n            <div class=\"cs-portfolio-header-meta\">\r\n                <img decoding=\"async\" alt=\"\" class=\"attachment-featuredImageCropped\" src=\"https:\/\/demo.exptheme.com\/yamato\/wp-content\/uploads\/2014\/11\/7-300x200_c.jpg\" \/>                <div class=\"link-wrap\">\r\n                    <a data-csrel=\"tooltip\" data-original-title=\"Large Image\" href=\"https:\/\/demo.exptheme.com\/yamato\/wp-content\/uploads\/2014\/11\/7-1024x700.jpg\" class=\"cs-zoom colorbox\"><span class=\"cs-meta-zoom\"><i class=\"fa fa-expand\"><\/i>\r\n<\/span><\/a><a data-csrel=\"tooltip\" data-original-title=\"Read more\" class=\"cs-read-more\" title=\"\" href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio\/work7\/\" ><i class=\"fa fa-sign-out\"><\/i><\/a>                <\/div>\r\n            <\/div>    \r\n            <div class=\"cs-portfolio-content-wrap\" style=\"background-color:;\">\r\n                <div class=\"cs-portfolio-meta-box\">\r\n                    <div class=\"cs-portfolio-category\"><a href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio_category\/work\/\" rel=\"tag\">Web Design<\/a><\/div><h4 class=\"cs-portfolio-title\"><a style=\"color:!important;\" title=\"Work7\" href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio\/work7\/\" >Work7<\/a><\/h4>                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/article>\r\n<\/div>\r\n<\/div><div class='cs-portfolio-item class-test print-design ' data-id='9847'><style type=\"text\/css\" scoped>\r\n    #cs_portfolio_1 .cs-portfolio-container a{\r\n            }\r\n    #cs_portfolio_1 .cs-portfolio-container a:hover{\r\n            }\r\n    #cs_portfolio_1.cs-portfolio{\r\n        margin: 0 -10px;    }\r\n<\/style>\r\n<div class=\"cs-portfolio-container\" style=\"margin:10px;\">\r\n    <article id=\"post-9847\" class=\"post-9847 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-print-design\">\r\n        <div class=\"cs-portfolio-header \">\r\n            <div class=\"cs-portfolio-header-meta\">\r\n                <img decoding=\"async\" alt=\"\" class=\"attachment-featuredImageCropped\" src=\"https:\/\/demo.exptheme.com\/yamato\/wp-content\/uploads\/2014\/11\/6-300x200_c.jpg\" \/>                <div class=\"link-wrap\">\r\n                    <a data-csrel=\"tooltip\" data-original-title=\"Large Image\" href=\"https:\/\/demo.exptheme.com\/yamato\/wp-content\/uploads\/2014\/11\/6-1024x700.jpg\" class=\"cs-zoom colorbox\"><span class=\"cs-meta-zoom\"><i class=\"fa fa-expand\"><\/i>\r\n<\/span><\/a><a data-csrel=\"tooltip\" data-original-title=\"Read more\" class=\"cs-read-more\" title=\"\" href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio\/work6\/\" ><i class=\"fa fa-sign-out\"><\/i><\/a>                <\/div>\r\n            <\/div>    \r\n            <div class=\"cs-portfolio-content-wrap\" style=\"background-color:;\">\r\n                <div class=\"cs-portfolio-meta-box\">\r\n                    <div class=\"cs-portfolio-category\"><a href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio_category\/print-design\/\" rel=\"tag\">Print Design<\/a><\/div><h4 class=\"cs-portfolio-title\"><a style=\"color:!important;\" title=\"Work6\" href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio\/work6\/\" >Work6<\/a><\/h4>                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/article>\r\n<\/div>\r\n<\/div><div class='cs-portfolio-item class-test print-design ' data-id='9846'><style type=\"text\/css\" scoped>\r\n    #cs_portfolio_1 .cs-portfolio-container a{\r\n            }\r\n    #cs_portfolio_1 .cs-portfolio-container a:hover{\r\n            }\r\n    #cs_portfolio_1.cs-portfolio{\r\n        margin: 0 -10px;    }\r\n<\/style>\r\n<div class=\"cs-portfolio-container\" style=\"margin:10px;\">\r\n    <article id=\"post-9846\" class=\"post-9846 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-print-design\">\r\n        <div class=\"cs-portfolio-header \">\r\n            <div class=\"cs-portfolio-header-meta\">\r\n                <img decoding=\"async\" alt=\"\" class=\"attachment-featuredImageCropped\" src=\"https:\/\/demo.exptheme.com\/yamato\/wp-content\/uploads\/2014\/11\/5-300x200_c.jpg\" \/>                <div class=\"link-wrap\">\r\n                    <a data-csrel=\"tooltip\" data-original-title=\"Large Image\" href=\"https:\/\/demo.exptheme.com\/yamato\/wp-content\/uploads\/2014\/11\/5-1024x700.jpg\" class=\"cs-zoom colorbox\"><span class=\"cs-meta-zoom\"><i class=\"fa fa-expand\"><\/i>\r\n<\/span><\/a><a data-csrel=\"tooltip\" data-original-title=\"Read more\" class=\"cs-read-more\" title=\"\" href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio\/work5\/\" ><i class=\"fa fa-sign-out\"><\/i><\/a>                <\/div>\r\n            <\/div>    \r\n            <div class=\"cs-portfolio-content-wrap\" style=\"background-color:;\">\r\n                <div class=\"cs-portfolio-meta-box\">\r\n                    <div class=\"cs-portfolio-category\"><a href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio_category\/print-design\/\" rel=\"tag\">Print Design<\/a><\/div><h4 class=\"cs-portfolio-title\"><a style=\"color:!important;\" title=\"Work5\" href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio\/work5\/\" >Work5<\/a><\/h4>                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/article>\r\n<\/div>\r\n<\/div><div class='cs-portfolio-item class-test print-design ' data-id='9845'><style type=\"text\/css\" scoped>\r\n    #cs_portfolio_1 .cs-portfolio-container a{\r\n            }\r\n    #cs_portfolio_1 .cs-portfolio-container a:hover{\r\n            }\r\n    #cs_portfolio_1.cs-portfolio{\r\n        margin: 0 -10px;    }\r\n<\/style>\r\n<div class=\"cs-portfolio-container\" style=\"margin:10px;\">\r\n    <article id=\"post-9845\" class=\"post-9845 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-print-design\">\r\n        <div class=\"cs-portfolio-header \">\r\n            <div class=\"cs-portfolio-header-meta\">\r\n                <img decoding=\"async\" alt=\"\" class=\"attachment-featuredImageCropped\" src=\"https:\/\/demo.exptheme.com\/yamato\/wp-content\/uploads\/2014\/11\/4-300x200_c.jpg\" \/>                <div class=\"link-wrap\">\r\n                    <a data-csrel=\"tooltip\" data-original-title=\"Large Image\" href=\"https:\/\/demo.exptheme.com\/yamato\/wp-content\/uploads\/2014\/11\/4-1024x700.jpg\" class=\"cs-zoom colorbox\"><span class=\"cs-meta-zoom\"><i class=\"fa fa-expand\"><\/i>\r\n<\/span><\/a><a data-csrel=\"tooltip\" data-original-title=\"Read more\" class=\"cs-read-more\" title=\"\" href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio\/work4\/\" ><i class=\"fa fa-sign-out\"><\/i><\/a>                <\/div>\r\n            <\/div>    \r\n            <div class=\"cs-portfolio-content-wrap\" style=\"background-color:;\">\r\n                <div class=\"cs-portfolio-meta-box\">\r\n                    <div class=\"cs-portfolio-category\"><a href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio_category\/print-design\/\" rel=\"tag\">Print Design<\/a><\/div><h4 class=\"cs-portfolio-title\"><a style=\"color:!important;\" title=\"Work4\" href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio\/work4\/\" >Work4<\/a><\/h4>                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/article>\r\n<\/div>\r\n<\/div><div class='cs-portfolio-item class-test logo-design ' data-id='9844'><style type=\"text\/css\" scoped>\r\n    #cs_portfolio_1 .cs-portfolio-container a{\r\n            }\r\n    #cs_portfolio_1 .cs-portfolio-container a:hover{\r\n            }\r\n    #cs_portfolio_1.cs-portfolio{\r\n        margin: 0 -10px;    }\r\n<\/style>\r\n<div class=\"cs-portfolio-container\" style=\"margin:10px;\">\r\n    <article id=\"post-9844\" class=\"post-9844 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-logo-design\">\r\n        <div class=\"cs-portfolio-header \">\r\n            <div class=\"cs-portfolio-header-meta\">\r\n                <img decoding=\"async\" alt=\"\" class=\"attachment-featuredImageCropped\" src=\"https:\/\/demo.exptheme.com\/yamato\/wp-content\/uploads\/2014\/11\/3-300x200_c.jpg\" \/>                <div class=\"link-wrap\">\r\n                    <a data-csrel=\"tooltip\" data-original-title=\"Large Image\" href=\"https:\/\/demo.exptheme.com\/yamato\/wp-content\/uploads\/2014\/11\/3-1024x700.jpg\" class=\"cs-zoom colorbox\"><span class=\"cs-meta-zoom\"><i class=\"fa fa-expand\"><\/i>\r\n<\/span><\/a><a data-csrel=\"tooltip\" data-original-title=\"Read more\" class=\"cs-read-more\" title=\"\" href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio\/work3\/\" ><i class=\"fa fa-sign-out\"><\/i><\/a>                <\/div>\r\n            <\/div>    \r\n            <div class=\"cs-portfolio-content-wrap\" style=\"background-color:;\">\r\n                <div class=\"cs-portfolio-meta-box\">\r\n                    <div class=\"cs-portfolio-category\"><a href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio_category\/logo-design\/\" rel=\"tag\">Logo Design<\/a><\/div><h4 class=\"cs-portfolio-title\"><a style=\"color:!important;\" title=\"Work3\" href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio\/work3\/\" >Work3<\/a><\/h4>                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/article>\r\n<\/div>\r\n<\/div><div class='cs-portfolio-item class-test logo-design ' data-id='9842'><style type=\"text\/css\" scoped>\r\n    #cs_portfolio_1 .cs-portfolio-container a{\r\n            }\r\n    #cs_portfolio_1 .cs-portfolio-container a:hover{\r\n            }\r\n    #cs_portfolio_1.cs-portfolio{\r\n        margin: 0 -10px;    }\r\n<\/style>\r\n<div class=\"cs-portfolio-container\" style=\"margin:10px;\">\r\n    <article id=\"post-9842\" class=\"post-9842 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-logo-design\">\r\n        <div class=\"cs-portfolio-header \">\r\n            <div class=\"cs-portfolio-header-meta\">\r\n                <img decoding=\"async\" alt=\"\" class=\"attachment-featuredImageCropped\" src=\"https:\/\/demo.exptheme.com\/yamato\/wp-content\/uploads\/2014\/11\/2-300x200_c.jpg\" \/>                <div class=\"link-wrap\">\r\n                    <a data-csrel=\"tooltip\" data-original-title=\"Large Image\" href=\"https:\/\/demo.exptheme.com\/yamato\/wp-content\/uploads\/2014\/11\/2-1024x700.jpg\" class=\"cs-zoom colorbox\"><span class=\"cs-meta-zoom\"><i class=\"fa fa-expand\"><\/i>\r\n<\/span><\/a><a data-csrel=\"tooltip\" data-original-title=\"Read more\" class=\"cs-read-more\" title=\"\" href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio\/work2\/\" ><i class=\"fa fa-sign-out\"><\/i><\/a>                <\/div>\r\n            <\/div>    \r\n            <div class=\"cs-portfolio-content-wrap\" style=\"background-color:;\">\r\n                <div class=\"cs-portfolio-meta-box\">\r\n                    <div class=\"cs-portfolio-category\"><a href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio_category\/logo-design\/\" rel=\"tag\">Logo Design<\/a><\/div><h4 class=\"cs-portfolio-title\"><a style=\"color:!important;\" title=\"Work2\" href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio\/work2\/\" >Work2<\/a><\/h4>                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/article>\r\n<\/div>\r\n<\/div><div class='cs-portfolio-item class-test logo-design ' data-id='9832'><style type=\"text\/css\" scoped>\r\n    #cs_portfolio_1 .cs-portfolio-container a{\r\n            }\r\n    #cs_portfolio_1 .cs-portfolio-container a:hover{\r\n            }\r\n    #cs_portfolio_1.cs-portfolio{\r\n        margin: 0 -10px;    }\r\n<\/style>\r\n<div class=\"cs-portfolio-container\" style=\"margin:10px;\">\r\n    <article id=\"post-9832\" class=\"post-9832 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-logo-design\">\r\n        <div class=\"cs-portfolio-header \">\r\n            <div class=\"cs-portfolio-header-meta\">\r\n                <img decoding=\"async\" alt=\"\" class=\"attachment-featuredImageCropped\" src=\"https:\/\/demo.exptheme.com\/yamato\/wp-content\/uploads\/2014\/11\/1-300x200_c.jpg\" \/>                <div class=\"link-wrap\">\r\n                    <a data-csrel=\"tooltip\" data-original-title=\"Large Image\" href=\"https:\/\/demo.exptheme.com\/yamato\/wp-content\/uploads\/2014\/11\/1-1024x700.jpg\" class=\"cs-zoom colorbox\"><span class=\"cs-meta-zoom\"><i class=\"fa fa-expand\"><\/i>\r\n<\/span><\/a><a data-csrel=\"tooltip\" data-original-title=\"Read more\" class=\"cs-read-more\" title=\"\" href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio\/work1\/\" ><i class=\"fa fa-sign-out\"><\/i><\/a>                <\/div>\r\n            <\/div>    \r\n            <div class=\"cs-portfolio-content-wrap\" style=\"background-color:;\">\r\n                <div class=\"cs-portfolio-meta-box\">\r\n                    <div class=\"cs-portfolio-category\"><a href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio_category\/logo-design\/\" rel=\"tag\">Logo Design<\/a><\/div><h4 class=\"cs-portfolio-title\"><a style=\"color:!important;\" title=\"Work1\" href=\"https:\/\/demo.exptheme.com\/yamato\/portfolio\/work1\/\" >Work1<\/a><\/h4>                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/article>\r\n<\/div>\r\n<\/div><\/div>[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row css=&#8221;.vc_custom_1654055571763{padding-top: 40px !important;padding-bottom: 70px !important;}&#8221;][vc_column][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-10073","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/demo.exptheme.com\/yamato\/wp-json\/wp\/v2\/pages\/10073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demo.exptheme.com\/yamato\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/demo.exptheme.com\/yamato\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/demo.exptheme.com\/yamato\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/demo.exptheme.com\/yamato\/wp-json\/wp\/v2\/comments?post=10073"}],"version-history":[{"count":2,"href":"https:\/\/demo.exptheme.com\/yamato\/wp-json\/wp\/v2\/pages\/10073\/revisions"}],"predecessor-version":[{"id":10945,"href":"https:\/\/demo.exptheme.com\/yamato\/wp-json\/wp\/v2\/pages\/10073\/revisions\/10945"}],"wp:attachment":[{"href":"https:\/\/demo.exptheme.com\/yamato\/wp-json\/wp\/v2\/media?parent=10073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}